{"id":930,"date":"2013-05-29T16:13:01","date_gmt":"2013-05-29T18:13:01","guid":{"rendered":"http:\/\/www.encontragranjaviana.com.br\/noticias\/?p=930"},"modified":"2019-04-29T16:22:15","modified_gmt":"2019-04-29T18:22:15","slug":"der-nao-confirma-novos-radares-na-raposo-tavares","status":"publish","type":"post","link":"https:\/\/www.encontragranjaviana.com.br\/sobre\/der-nao-confirma-novos-radares-na-raposo-tavares\/","title":{"rendered":"DER n\u00e3o confirma novos radares na Raposo Tavares"},"content":{"rendered":"<div class=\"15401c187b342417d42857c0d7dac0c7\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>A fiscaliza\u00e7\u00e3o de excesso de velocidade nas estradas de S\u00e3o Paulo vai mais que dobrar at\u00e9 o fim deste ano. Uma nova licita\u00e7\u00e3o prev\u00ea a contrata\u00e7\u00e3o de 549 radares fixos para as rodovias administradas pelo Departamento de Estradas de Rodagem (DER) em todas as regi\u00f5es do Estado.<\/p>\n<p>Desses, 114 ser\u00e3o do tipo lombada eletr\u00f4nica, com registro digital da velocidade, e 124 ter\u00e3o dispositivo para a leitura das placas dos ve\u00edculos e c\u00e1lculo do tempo da viagem (cobran\u00e7a ponto a ponto). Atualmente, em todas as rodovias estaduais operam 345 radares fixos, dos quais 183 est\u00e3o em estradas do DER e 162 em rodovias concedidas \u00e0 iniciativa privada. Com os novos radares, o n\u00famero chegar\u00e1 a 894 medidores fixos.<\/p>\n<p>Em nota enviada ao site\u00a0<em>cotiatododia<\/em>, o DER diz que ainda n\u00e3o possui informa\u00e7\u00e3o regionalizada e n\u00e3o confirma a instala\u00e7\u00e3o de radares na Rodovia Raposo Tavares no trecho entre S\u00e3o Paulo e a cidade de Cotia.<\/p>\n<p>Um levantamento feito pelo DER entre 2005 e 2011 identificou mais de 500 pontos cr\u00edticos, com maior incid\u00eancia de excesso de velocidade pelos motoristas, nas 144 rodovias paulistas ainda sem bases fixas de radar. O \u00f3rg\u00e3o estadual administra 16,4 mil quil\u00f4metros de rodovias e a m\u00e9dia \u00e9 de um radar fixo a cada 89,6 km. O controle da velocidade \u00e9 quase tr\u00eas vezes menor nessas estradas do que nas rodovias sob concess\u00e3o. Nos 6,3 mil km de malha concedida, a m\u00e9dia \u00e9 de um equipamento fixo a cada 38,8 km.<\/p>\n<p><strong>Edital e instala\u00e7\u00e3o<\/strong>. O edital para contrata\u00e7\u00e3o de equipamentos possui 14 lotes que abrangem as regi\u00f5es de Campinas, Itapetininga, Bauru, Araraquara, Cubat\u00e3o, Taubat\u00e9, Assis, Ribeir\u00e3o Preto, S\u00e3o Jos\u00e9 do Rio Preto, S\u00e3o Paulo, Ara\u00e7atuba, Presidente Prudente, Rio Claro e Barretos. Cinco cons\u00f3rcios de empresas do setor se habilitaram para a disputa: SVS, Monitoramento Paulista, CTL Monitoramento, PLP Tr\u00e2nsito Seguro e Cons\u00f3rcio Paulista de Fiscaliza\u00e7\u00e3o Rodovi\u00e1ria. Na abertura dos envelopes, o Cons\u00f3rcio SVS apresentou o menor pre\u00e7o para todos os lotes, totalizando cerca de R$ 40 milh\u00f5es. Os outros concorrentes entraram com recursos que ainda ser\u00e3o julgados.<\/p>\n<p>Conforme Pelissioni, a previs\u00e3o \u00e9 de que os contratos sejam assinados em julho e os radares comecem a ser instalados entre agosto e setembro. De acordo com o superintendente, o DER n\u00e3o prev\u00ea a contrata\u00e7\u00e3o de mais radares m\u00f3veis.<\/p>\n<p><em>Fonte: Cotiatododia<\/em><\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>A fiscaliza\u00e7\u00e3o de excesso de velocidade nas estradas de S\u00e3o Paulo vai mais que dobrar at\u00e9 o fim deste ano. Uma nova licita\u00e7\u00e3o prev\u00ea a contrata\u00e7\u00e3o de 549 radares fixos para as rodovias administradas pelo Departamento de Estradas de Rodagem (DER) em todas as regi\u00f5es do Estado. Desses, 114 ser\u00e3o do tipo lombada eletr\u00f4nica, com registro digital da velocidade, e 124 ter\u00e3o dispositivo para a leitura das placas dos ve\u00edculos e c\u00e1lculo do tempo da viagem (cobran\u00e7a ponto a ponto). Atualmente, em todas as rodovias estaduais operam 345 radares fixos, dos quais 183 est\u00e3o em estradas do DER e 162 <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[14],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/posts\/930"}],"collection":[{"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=930"}],"version-history":[{"count":0,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/posts\/930\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=930"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=930"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=930"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}