{"id":1863,"date":"2013-11-15T00:14:10","date_gmt":"2013-11-15T02:14:10","guid":{"rendered":"http:\/\/www.encontragranjaviana.com.br\/noticias\/?p=1863"},"modified":"2019-04-29T16:22:12","modified_gmt":"2019-04-29T18:22:12","slug":"centro-cultural-realiza-workshop-de-fotografia-na-granja-viana","status":"publish","type":"post","link":"https:\/\/www.encontragranjaviana.com.br\/sobre\/centro-cultural-realiza-workshop-de-fotografia-na-granja-viana\/","title":{"rendered":"Centro Cultural Wurth realiza workshop de fotografia na Granja Viana"},"content":{"rendered":"<div class=\"15401c187b342417d42857c0d7dac0c7\" data-index=\"1\" style=\"float: left; margin: 15px 15px 15px 0;\">\n<!-- EBR \/Novo-Bairro\/ 300x250 - pub-85 -->\r\n<ins class=\"adsbygoogle\"\r\n     style=\"display:inline-block;width:300px;height:250px\"\r\n     data-ad-client=\"ca-pub-8585364105181520\"\r\n     data-ad-slot=\"4691134188\"><\/ins>\r\n<script>\r\n(adsbygoogle = window.adsbygoogle || []).push({});\r\n<\/script>\n<\/div>\n<p>O Centro Cultural Wurth apresenta um workshop de fotografia intitulado \u201cAntes do Click, negocia\u00e7\u00e3o entre a realidade e o imagin\u00e1rio\u201d, ministrado em dois dias, 23 e 30 de novembro, das 9h \u00e0s 18h, por Adi Leite.<\/p>\n<p>O fot\u00f3grafo Adi tem como objetivo investigar os diversos pensamentos que sustentam as quest\u00f5es antes do click e que fundamentam a hist\u00f3ria da fotografia, com a finalidade de contribuir para a forma\u00e7\u00e3o de um pensamento cr\u00edtico sobre a imagem e tamb\u00e9m auxiliar na elabora\u00e7\u00e3o de um projeto gr\u00e1fico.<\/p>\n<p>Com o workshop dividido em duas etapas, Adi aborda, na primeira, a hist\u00f3ria da fotografia, suas quest\u00f5es e seu percurso dentro da hist\u00f3ria da humanidade atrav\u00e9s da linha do tempo da arte, a partir do in\u00edcio do s\u00e9culo XIX.<\/p>\n<p>A segunda etapa trar\u00e1 informa\u00e7\u00f5es de como auxiliar na elabora\u00e7\u00e3o de um trabalho fotogr\u00e1fico, por meio de uma inicia\u00e7\u00e3o aos elementos da t\u00e9cnica fotogr\u00e1fica, e a an\u00e1lise do trabalho de alguns fot\u00f3grafos, visando a construir um repert\u00f3rio suficiente para que o aluno comece a desenvolver suas pr\u00f3prias ideias.<\/p>\n<p>O investimento deste workshop tem o valor de R$350, inclusos estrutura, estacionamento, eventual material did\u00e1tico impresso e coffe break. H\u00e1 um desconto de R$30 para os alunos que se inscreverem at\u00e9 o dia 14 de novembro. O valor pode ser pago \u00e0 vista, ou em 2 parcelas iguais, em cheque ou dinheiro.<\/p>\n<p><strong>Data:<\/strong> 23 e 30 de novembro<br \/>\n<strong>Hor\u00e1rio:<\/strong> das 9 \u00e0s 18h<br \/>\n<strong>Local: <\/strong><a title=\"Centro Cultural Wurth\" href=\"http:\/\/www.encontragranjaviana.com.br\/granja-viana\/centro-cultural-wurth-na-granja-vianna.shtml\" target=\"_blank\">Centro Cultural Wurth<strong><\/strong><\/a><br \/>\n<strong>Endere\u00e7o: <\/strong>Rua Adolf Wurth, 557 &#8211; Jardim S\u00e3o Vicente, Cotia<strong><\/strong><br \/>\n<strong>Classifica\u00e7\u00e3o:<\/strong> Livre<br \/>\n<strong>Dura\u00e7\u00e3o:<\/strong> 8h<br \/>\n<strong>Inscri\u00e7\u00f5es:<\/strong> Via email (eventos@wurth.com.br) ou telefone (4612-8100) com D\u00e9borah<\/p>\n\n<div style=\"font-size: 0px; height: 0px; line-height: 0px; margin: 0; padding: 0; clear: both;\"><\/div>","protected":false},"excerpt":{"rendered":"<p>O Centro Cultural Wurth apresenta um workshop de fotografia intitulado \u201cAntes do Click, negocia\u00e7\u00e3o entre a realidade e o imagin\u00e1rio\u201d, ministrado em dois dias, 23 e 30 de novembro, das 9h \u00e0s 18h, por Adi Leite. O fot\u00f3grafo Adi tem como objetivo investigar os diversos pensamentos que sustentam as quest\u00f5es antes do click e que fundamentam a hist\u00f3ria da fotografia, com a finalidade de contribuir para a forma\u00e7\u00e3o de um pensamento cr\u00edtico sobre a imagem e tamb\u00e9m auxiliar na elabora\u00e7\u00e3o de um projeto gr\u00e1fico. Com o workshop dividido em duas etapas, Adi aborda, na primeira, a hist\u00f3ria da fotografia, suas <\/p>\n","protected":false},"author":1,"featured_media":0,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[6],"tags":[],"aioseo_notices":[],"_links":{"self":[{"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1863"}],"collection":[{"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/comments?post=1863"}],"version-history":[{"count":0,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/posts\/1863\/revisions"}],"wp:attachment":[{"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/media?parent=1863"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/categories?post=1863"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/www.encontragranjaviana.com.br\/sobre\/wp-json\/wp\/v2\/tags?post=1863"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}